{"id":4344,"date":"2020-10-17T10:30:01","date_gmt":"2020-10-17T08:30:01","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=4344"},"modified":"2020-10-20T08:18:37","modified_gmt":"2020-10-20T06:18:37","slug":"gottesdienst-18-oktober-erloeserkirche","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/","title":{"rendered":"Gottesdienst, 18.10.:<br>Live oder auf Youtube"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4344\" class=\"elementor elementor-4344\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd68469 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd68469\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cce0ec8\" data-id=\"cce0ec8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cac814 elementor-widget elementor-widget-text-editor\" data-id=\"1cac814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.youtube.com\/channel\/UCHXWpLBsI8jKJa0Jh2UklTg\/playlists\"><img decoding=\"async\" src=\"https:\/\/images.vexels.com\/media\/users\/3\/141532\/isolated\/lists\/3a36614d8dde3aa7ee06398cb6dc80cb-youtube-gummi-symbol.png\" alt=\"Youtube-Play-Button-Logo - Transparenter PNG und SVG-Vektor\" width=\"50\" height=\"50\" data-noaft=\"1\" \/><\/a>2xGottesdienst am 18.10.:<br \/>Live im Kreuzgang <b>oder<\/b> auf Youtube aus der Erl\u00f6serkirche<\/p><p>Der strikte Lockdown wird am Sonntag, 18. Oktober 2020, aufgehoben. Wir feiern dann im Kreuzgang der Erl\u00f6serkirche Gottesdienst: Open Air, d.h. bis zu 20 Menschen d\u00fcrfen dabeisein.<\/p><p>Der vorab f\u00fcr den Sonntag vorbereitete Gottesdienst wird ab Sonntagmorgen auf unserem Gottesdienstkanal bei Youtube zu sehen sein<b>. <\/b>Herzliche Einladung, dort dabeizusein und so hoffenlich gedanklich und geistlich beim Gottesdienst in Jerusalem teilzunehmen.<b><\/b><\/p><ul><li><b><span style=\"font-size: 12pt; line-height: 22.079999923706055px; font-family: 'Source Sans Pro', sans-serif;\"><a style=\"color: #0563c1; text-decoration: underline;\" title=\"https:\/\/is.gd\/CmUTFn\" href=\"https:\/\/is.gd\/CmUTFn\">https:\/\/is.gd\/CmUTFn.<\/a><\/span><\/b><\/li><\/ul><p><strong>Gestaltung:<\/strong><\/p><ul><li>Predigt: Propst <em>Joachim Lenz<br \/><\/em><\/li><li>Lesungen und Gebete: <em>Michael Mohrmann<br \/><\/em><\/li><li>Musik: Prof. <em>Hartmut Rohmeye,<\/em> an der Orgel der Reformierten Kirche L\u00fcbeck<\/li><\/ul><p><strong>Bibeltexte<\/strong>: Psalm 119,121-128; Epheser 4,22-32 (Predigttext)<\/p><p><strong>Music<\/strong>: aus dem Ev. Gesangbuch EG 324; 369; 295; 171.<\/p><p>\u00a0<\/p><p><strong>Kollektenbitte<\/strong><\/p><blockquote><p>Wir bitten, statt einer Kollekte im Pr\u00e4senz-Gottesdienst eine Spende f\u00fcr unseren Sozialfonds zu \u00fcberweisen:<\/p><p>Evangelische Gemeinde Deutscher Sprache zu Jerusalem<\/p><p><strong>Stichwort \u201eSozialfonds\u201c<br \/><\/strong>IBAN DE88 5206 0410 0004 1076 32<br \/>BIC GENODEF1EK1 (Evangelische Bank Kassel)<\/p><p>Mit unserem Sozialfonds unterst\u00fctzen wir ausschlie\u00dflich in Not geratene Menschen. Wenn Sie uns Ihre Postanschrift angeben, schicken wir Ihnen auch gerne eine Spendenquittung zu. Schon jetzt bedanken wir uns im Namen derer, denen die Spende zugute kommt.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p><b>2 x Gottesdienst in Jerusalem:<\/b><br><br \/>\nmit dem Ende des strikten Lockdowns live im Kreuzgang \u2013<br \/>\n<i>oder<\/i> ab Sonntagmorgen um 7:30 Uhr auf YouTube aus der Erl\u00f6serkirche.<br><br \/>\nUnseren Gottesdienst-Kanal gibt es bei Youtube unter<br><a href=\"https:\/\/is.gd\/CmUTFn\">https:\/\/is.gd\/CmUTFn<\/a><br \/>\nPredigttext ist Epheser 4,22-32.<\/p>","protected":false},"author":6,"featured_media":4350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19,181,173,171],"tags":[],"class_list":["post-4344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-allgemein-en","category-erloeserkirche","category-gemeinde","category-gottesdienst","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gottesdienst, 18.10.:Live oder auf Youtube - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gottesdienst, 18.10.:Live oder auf Youtube - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"2 x Gottesdienst in Jerusalem: mit dem Ende des strikten Lockdowns live im Kreuzgang \u2013 oder ab Sonntagmorgen um 7:30 Uhr auf YouTube aus der Erl\u00f6serkirche. Unseren Gottesdienst-Kanal gibt es bei Youtube unterhttps:\/\/is.gd\/CmUTFn Predigttext ist Epheser 4,22-32.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-17T08:30:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-20T06:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2020\/10\/ErlK-Kuppel-Einl-GoDi-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joachim Lenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joachim Lenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/\"},\"author\":{\"name\":\"Joachim Lenz\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\"},\"headline\":\"Gottesdienst, 18.10.: Live oder auf Youtube\",\"datePublished\":\"2020-10-17T08:30:01+00:00\",\"dateModified\":\"2020-10-20T06:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/\"},\"wordCount\":188,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ErlK-Kuppel-Einl-GoDi-1.jpg\",\"articleSection\":[\"Allgemein\",\"Allgemein\",\"Erl\u00f6serkirche\",\"Gemeinde\",\"Gottesdienst\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/\",\"name\":\"Gottesdienst, 18.10.: Live oder auf Youtube - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ErlK-Kuppel-Einl-GoDi-1.jpg\",\"datePublished\":\"2020-10-17T08:30:01+00:00\",\"dateModified\":\"2020-10-20T06:18:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ErlK-Kuppel-Einl-GoDi-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/ErlK-Kuppel-Einl-GoDi-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2020\\\/10\\\/17\\\/gottesdienst-18-oktober-erloeserkirche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gottesdienst, 18.10.:Live oder auf Youtube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\",\"name\":\"Joachim Lenz\",\"sameAs\":[\"http:\\\/\\\/evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/propst-jl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gottesdienst, 18.10.:Live oder auf Youtube - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/","og_locale":"en_GB","og_type":"article","og_title":"Gottesdienst, 18.10.:Live oder auf Youtube - Evangelisch in Jerusalem","og_description":"2 x Gottesdienst in Jerusalem: mit dem Ende des strikten Lockdowns live im Kreuzgang \u2013 oder ab Sonntagmorgen um 7:30 Uhr auf YouTube aus der Erl\u00f6serkirche. Unseren Gottesdienst-Kanal gibt es bei Youtube unterhttps:\/\/is.gd\/CmUTFn Predigttext ist Epheser 4,22-32.","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2020-10-17T08:30:01+00:00","article_modified_time":"2020-10-20T06:18:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2020\/10\/ErlK-Kuppel-Einl-GoDi-1.jpg","type":"image\/jpeg"}],"author":"Joachim Lenz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Joachim Lenz","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/"},"author":{"name":"Joachim Lenz","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607"},"headline":"Gottesdienst, 18.10.: Live oder auf Youtube","datePublished":"2020-10-17T08:30:01+00:00","dateModified":"2020-10-20T06:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/"},"wordCount":188,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2020\/10\/ErlK-Kuppel-Einl-GoDi-1.jpg","articleSection":["Allgemein","Allgemein","Erl\u00f6serkirche","Gemeinde","Gottesdienst"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/","name":"Gottesdienst, 18.10.: Live oder auf Youtube - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2020\/10\/ErlK-Kuppel-Einl-GoDi-1.jpg","datePublished":"2020-10-17T08:30:01+00:00","dateModified":"2020-10-20T06:18:37+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2020\/10\/ErlK-Kuppel-Einl-GoDi-1.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2020\/10\/ErlK-Kuppel-Einl-GoDi-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2020\/10\/17\/gottesdienst-18-oktober-erloeserkirche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Gottesdienst, 18.10.:Live oder auf Youtube"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607","name":"Joachim Lenz","sameAs":["http:\/\/evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/propst-jl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/4344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=4344"}],"version-history":[{"count":2,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/4344\/revisions"}],"predecessor-version":[{"id":4406,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/4344\/revisions\/4406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/4350"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=4344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=4344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=4344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}