{"id":21033,"date":"2025-09-22T17:23:47","date_gmt":"2025-09-22T14:23:47","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=21033"},"modified":"2025-09-22T17:23:49","modified_gmt":"2025-09-22T14:23:49","slug":"5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/","title":{"rendered":"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum"},"content":{"rendered":"<p>In diesem Jahr feiert das Gro\u00dfe Glaubensbekenntnis des Konzils von Niz\u00e4a sein 1.700stes Jubil\u00e4um. Die Kirchen in Jerusalem feiern das zusammen mit einem Konzert, in dem Ch\u00f6re und Einzelne aus den verschiedenen Kirchen Lieder aus ihren Traditionen beisteuern.<\/p>","protected":false},"excerpt":{"rendered":"<p>In diesem Jahr feiert das Gro\u00dfe Glaubensbekenntnis des Konzils von Niz\u00e4a sein 1.700stes Jubil\u00e4um. Die Kirchen in Jerusalem feiern das zusammen mit einem Konzert, in dem Ch\u00f6re und Einzelne aus den verschiedenen Kirchen Lieder aus ihren Traditionen beisteuern.<\/p>","protected":false},"author":6,"featured_media":21034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19,173,242,194,178,220,174],"tags":[],"class_list":["post-21033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-allgemein-en","category-gemeinde","category-jerusalem","category-konzert","category-oecumene","category-topnachricht","category-veranstaltung","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"In diesem Jahr feiert das Gro\u00dfe Glaubensbekenntnis des Konzils von Niz\u00e4a sein 1.700stes Jubil\u00e4um. Die Kirchen in Jerusalem feiern das zusammen mit einem Konzert, in dem Ch\u00f6re und Einzelne aus den verschiedenen Kirchen Lieder aus ihren Traditionen beisteuern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T14:23:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T14:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joachim Lenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joachim Lenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/\"},\"author\":{\"name\":\"Joachim Lenz\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\"},\"headline\":\"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum\",\"datePublished\":\"2025-09-22T14:23:47+00:00\",\"dateModified\":\"2025-09-22T14:23:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg\",\"articleSection\":[\"Allgemein\",\"Allgemein\",\"Gemeinde\",\"Jerusalem\",\"Konzert\",\"\u00d6kumene\",\"Topnachricht\",\"Veranstaltung\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/\",\"name\":\"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg\",\"datePublished\":\"2025-09-22T14:23:47+00:00\",\"dateModified\":\"2025-09-22T14:23:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/22\\\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\",\"name\":\"Joachim Lenz\",\"sameAs\":[\"http:\\\/\\\/evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/propst-jl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/","og_locale":"en_GB","og_type":"article","og_title":"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum - Evangelisch in Jerusalem","og_description":"In diesem Jahr feiert das Gro\u00dfe Glaubensbekenntnis des Konzils von Niz\u00e4a sein 1.700stes Jubil\u00e4um. Die Kirchen in Jerusalem feiern das zusammen mit einem Konzert, in dem Ch\u00f6re und Einzelne aus den verschiedenen Kirchen Lieder aus ihren Traditionen beisteuern.","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2025-09-22T14:23:47+00:00","article_modified_time":"2025-09-22T14:23:49+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg","type":"image\/jpeg"}],"author":"Joachim Lenz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Joachim Lenz","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/"},"author":{"name":"Joachim Lenz","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607"},"headline":"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum","datePublished":"2025-09-22T14:23:47+00:00","dateModified":"2025-09-22T14:23:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/"},"wordCount":48,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg","articleSection":["Allgemein","Allgemein","Gemeinde","Jerusalem","Konzert","\u00d6kumene","Topnachricht","Veranstaltung"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/","name":"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg","datePublished":"2025-09-22T14:23:47+00:00","dateModified":"2025-09-22T14:23:49+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/oec_Concert-251005-armen.Mus-1-1-scaled.jpg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/22\/5-10-19-uhr-oekumenisches-chorkonzert-im-armenischen-museum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"5.10. 19 Uhr: \u00d6kumenisches Chorkonzert im Armenischen Museum"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607","name":"Joachim Lenz","sameAs":["http:\/\/evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/propst-jl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/21033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=21033"}],"version-history":[{"count":1,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/21033\/revisions"}],"predecessor-version":[{"id":21035,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/21033\/revisions\/21035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/21034"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=21033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=21033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=21033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}