{"id":20992,"date":"2025-09-05T09:42:18","date_gmt":"2025-09-05T06:42:18","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=20992"},"modified":"2025-10-30T08:39:31","modified_gmt":"2025-10-30T06:39:31","slug":"johannes-friedrich-20-6-1948-3-9-2025","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/","title":{"rendered":"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem"},"content":{"rendered":"<p><em>Johannes Friedrich war von 1985 bis 1991 Evangelischer Propst von Jerusalem. &#8220;Das war f\u00fcr mich, aber auch f\u00fcr meine Frau und meine T\u00f6chter die wichtigste Zeit in unserem Leben&#8221;, sagte er einmal im Blick auf die politisch schwierigen Jahre.  &#8220;Zum ersten Mal in meinem Leben durfte ich mich politisch zu diesem Konflikt nicht \u00e4u\u00dfern, weil ich ja f\u00fcr beide Seiten ansprechbar bleiben musste. Ich habe erst, als ich zur\u00fcck war, gemerkt, dass das doch eine unglaubliche Spannung war, in der ich gelebt habe.&#8221;<\/em><\/p>\n\n\n\n<p><em>Die Evangelische Gemeinde deutscher Sprache ist sehr dankbar f\u00fcr seinen Dienst in Jerusalem und f\u00fcr die bleibende Verbundenheit \u00fcber all die folgenden Jahrr hin. Wir bitten Gott um Trost f\u00fcr seine Frau und Familie und alle, die Johannes Friedrich nun vermissen.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u201eWarmherzig und weitsichtig\u201c<br>EKD und VELKD trauern um Landesbischof Johannes Friedrich<\/h3>\n\n\n\n<p>\u201eJohannes Friedrich war ein warmherziger und weitsichtiger Lutheraner, der zugleich den einzelnen Menschen und das Ganze der Theologie im Blick behielt\u201c, w\u00fcrdigt der Leitende Bischof der VELKD, Landesbischof Ralf Meister (Hannover), einen seiner Amtsvorg\u00e4nger, von dem er 2011 in sein Amt als Landesbischof der Landeskirche Hannovers eingef\u00fchrt wurde. \u201eWir trauern um einen beeindruckenden Geistlichen, der f\u00fcr die weltweite \u00d6kumene stritt und in seinen Predigten die st\u00e4rkende Kraft des Evangeliums betonte.\u201c<\/p>\n\n\n\n<p>Bisch\u00f6fin Kirsten Fehrs, die Ratsvorsitzende der EKD, erinnert sich: \u201eJohannes Friedrich sch\u00f6pfte seine Kraft aus einem unverbr\u00fcchlichen Glauben und wirkte segensreich in vielen kirchlichen Bereichen: im Verk\u00fcndigungsdienst als Pfarrer, Propst und Bischof, als Seelsorger und als gro\u00dfer Br\u00fcckenbauer in der \u00d6kumene und im interreligi\u00f6sen Dialog. Ich habe ihn als theologisch klar und menschlich zugewandt erlebt.\u201c<\/p>\n\n\n\n<p>Nach seinem Studium der evangelischen Theologie in Erlangen und T\u00fcbingen wurde der Sohn des evangelischen Theologen Prof. Gerhard Friedrich \u00fcber \u201eGott im Bruder\u201c promoviert und 1977 ordiniert. Nach einer Gemeindedienstzeit in N\u00fcrnberg wurde er 1985 als Propst an die Evangelische Gemeinde deutscher Sprache zu Jerusalem berufen, wo ihn auch Ralf Meister kennenlernte. Dort setzte er sich sehr f\u00fcr den interreligi\u00f6sen Dialog mit Juden und Muslimen ein und pflegte auch den interkonfessionellen Austausch mit vielen anderen christlichen Religionsgemeinschaften. 1991 kehrte er nach N\u00fcrnberg als Dekan zur\u00fcck und wurde 1999 zum Landesbischof der Evangelisch-Lutherischen Kirche in Bayern gew\u00e4hlt.<\/p>\n\n\n\n<p>2000 bis 2005 war Johannes Friedrich Catholica-Beauftragter der VELKD, bevor er 2005 zum Leitenden Bischof der VELKD gew\u00e4hlt wurde. Dieses Amt \u00fcbte er bis 2011 aus, und zwar in Personalunion mit dem Amt des Vorsitzenden des Deutschen Nationalkomitees des Lutherischen Weltbundes (DNK\/LWB). In diese Zeit fiel eine \u00f6kumenische Vesper, die er mit Papst Benedikt XVI. im Regensburger Dom feierte. Von 2002 bis 2013 geh\u00f6rte Johannes Friedrich auch dem Rat der Evangelischen Kirche in Deutschland (EKD) an.<\/p>\n\n\n\n<p>Nach seiner zw\u00f6lfj\u00e4hrigen Amtszeit als Landesbischof war Friedrich ab 2012 Gemeindepfarrer im fr\u00e4nkischen Bertholdsdorf, bevor er dann im September 2013 in den Ruhestand ging. Johannes Friedrich hinterl\u00e4sst eine Frau und zwei T\u00f6chter.<\/p>\n\n\n\n<p>Hannover, 3. September 2025<\/p>\n\n\n\n<p>Pressestelle der VELKD, <em>Frank Hofmann<\/em><br>Pressestelle der EKD, <em>Carsten Splitt<\/em><\/p>\n\n\n\n<p>Foto: (c) ekd.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Johannes Friedrich war von 1985 bis 1991 Evangelischer Propst von Jerusalem. &#8220;Das war f\u00fcr mich, aber auch f\u00fcr meine Frau und meine T\u00f6chter die wichtigste Zeit in unserem Leben&#8221;, sagte er einmal im Blick auf die politisch schwierigen Jahre. &#8220;Zum ersten Mal in meinem Leben durfte ich mich politisch zu diesem Konflikt nicht \u00e4u\u00dfern, weil &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem&#8221;<\/span><\/a><\/p>","protected":false},"author":6,"featured_media":20993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,173,179,276,220],"tags":[689,664,687,691,665,690,688],"class_list":["post-20992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-en","category-gemeinde","category-geschichte","category-person","category-topnachricht","tag-geschichte","tag-jerusalemstiftung","tag-johannes-friedrich","tag-landesbischof","tag-propst","tag-rueckblick","tag-verstorben","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Johannes Friedrich war von 1985 bis 1991 Evangelischer Propst von Jerusalem. &#8220;Das war f\u00fcr mich, aber auch f\u00fcr meine Frau und meine T\u00f6chter die wichtigste Zeit in unserem Leben&#8221;, sagte er einmal im Blick auf die politisch schwierigen Jahre. &#8220;Zum ersten Mal in meinem Leben durfte ich mich politisch zu diesem Konflikt nicht \u00e4u\u00dfern, weil &hellip; Continue reading &quot;Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T06:42:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T06:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joachim Lenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joachim Lenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/\"},\"author\":{\"name\":\"Joachim Lenz\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\"},\"headline\":\"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem\",\"datePublished\":\"2025-09-05T06:42:18+00:00\",\"dateModified\":\"2025-10-30T06:39:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/\"},\"wordCount\":510,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg\",\"keywords\":[\"Geschichte\",\"Jerusalemstiftung\",\"Johannes Friedrich\",\"Landesbischof\",\"Propst\",\"R\u00fcckblick\",\"verstorben\"],\"articleSection\":[\"Allgemein\",\"Gemeinde\",\"Geschichte\",\"Person\",\"Topnachricht\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/\",\"name\":\"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg\",\"datePublished\":\"2025-09-05T06:42:18+00:00\",\"dateModified\":\"2025-10-30T06:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/09\\\/05\\\/johannes-friedrich-20-6-1948-3-9-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\",\"name\":\"Joachim Lenz\",\"sameAs\":[\"http:\\\/\\\/evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/propst-jl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/","og_locale":"en_GB","og_type":"article","og_title":"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem - Evangelisch in Jerusalem","og_description":"Johannes Friedrich war von 1985 bis 1991 Evangelischer Propst von Jerusalem. &#8220;Das war f\u00fcr mich, aber auch f\u00fcr meine Frau und meine T\u00f6chter die wichtigste Zeit in unserem Leben&#8221;, sagte er einmal im Blick auf die politisch schwierigen Jahre. &#8220;Zum ersten Mal in meinem Leben durfte ich mich politisch zu diesem Konflikt nicht \u00e4u\u00dfern, weil &hellip; Continue reading \"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem\"","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2025-09-05T06:42:18+00:00","article_modified_time":"2025-10-30T06:39:31+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg","type":"image\/jpeg"}],"author":"Joachim Lenz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Joachim Lenz","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/"},"author":{"name":"Joachim Lenz","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607"},"headline":"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem","datePublished":"2025-09-05T06:42:18+00:00","dateModified":"2025-10-30T06:39:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/"},"wordCount":510,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg","keywords":["Geschichte","Jerusalemstiftung","Johannes Friedrich","Landesbischof","Propst","R\u00fcckblick","verstorben"],"articleSection":["Allgemein","Gemeinde","Geschichte","Person","Topnachricht"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/","name":"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg","datePublished":"2025-09-05T06:42:18+00:00","dateModified":"2025-10-30T06:39:31+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2025\/09\/250905_Johannes_Friedrichepd_00529896_rdax_60s-1.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/09\/05\/johannes-friedrich-20-6-1948-3-9-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Johannes Friedrich (20.6.1948-3.9.2025): Wichtigste Zeit war die in Jerusalem"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607","name":"Joachim Lenz","sameAs":["http:\/\/evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/propst-jl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=20992"}],"version-history":[{"count":5,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20992\/revisions"}],"predecessor-version":[{"id":21005,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20992\/revisions\/21005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/20993"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=20992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=20992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=20992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}