{"id":20744,"date":"2025-08-01T11:40:23","date_gmt":"2025-08-01T08:40:23","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=20744"},"modified":"2025-08-01T11:40:25","modified_gmt":"2025-08-01T08:40:25","slug":"unsere-veranstaltungen-im-august-2025","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/","title":{"rendered":"Unsere Veranstaltungen im August 2025"},"content":{"rendered":"<p>Sa, 02.08.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Pfarrerin Dr. Milena Hasselmann<\/p>\n\n\n\n<p>20.00 Uhr<br><strong>Breathing Space: Touching, peaceful musical moments in turbulent times<br>Konzert im Rahmen von Sounding Jerusalem Festival<\/strong><br>Tickets unter https:\/\/www.tickettailor.com\/events\/soundingjerusalem\/1717749<strong><br><\/strong>Mit Werken von Rossi, Bach, Cantata, Azarashvili<strong>\u2026<br><\/strong>Mark\u00e9ta Janou\u0161kov\u00e1 \u2013 Violine, Tommaso Benciolini \u2013 Fl\u00f6te, Armin Egger \u2013 Gitarre,<br>Erich Oskar Huetter \u2013 Cello, Johannes Maria Bogner \u2013 Orgel<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>So, 03.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst mit Abendmahl<br><\/strong>Predigt: Pfarrerin Dr. Milena Hasselmann<br>Mit Begr\u00fc\u00dfung der neuen Studierenden von \u201eStudium in Israel\u201c<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Sa, 09.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Propst Joachim Lenz<\/p>\n\n\n\n<p>So, 10.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst am 8. Sonntag nach Trinitatis<br><\/strong>Liturgie: Propst Joachim Lenz; Predigt: Auslandsbischof Frank Kopania<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 12.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.30 Uhr<br><strong>Requiem-Chorkonzert: Faure, Mozart<br><\/strong>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Sa, 16.08. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Propst Joachim Lenz<\/p>\n\n\n\n<p>So, 17.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst mit Abendmahl<\/strong><br>Predigt: Propst Joachim Lenz<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 19.08.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 20.00-22.00 Uhr<br><strong>Stummfilm mit Live-Musik: Slapstick Open Air<br><\/strong>Kurzfilme von und mit Charly Chaplin, Cooper, Laurel &amp; Hardy, Lloyd\u2026.<br>Ein entspannter Abend im Kreuzgang mit Lachen, Gespr\u00e4chen, Chips und Getr\u00e4nken.<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Kreuzgang der Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Sa, 23.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der <\/strong><strong>Lutheran Church of the Redeemer<\/strong><strong><br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Pfarrerin Ann-Kathrin Hasselmann<\/p>\n\n\n\n<p>So, 24.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst am 10. Sonntag nach Trinitatis<\/strong><br>Predigt: Pfarrerin Ann-Kathrin Hasselmann<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Sa, 30.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Propst Joachim Lenz<\/p>\n\n\n\n<p>So, 31.08.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst mit Abendmahl<\/strong><br>Predigt: Propst Joachim Lenz<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sa, 02.08.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 19.00 Uhr (18.00 Uhr deutscher Zeit)Friedensgebet per ZoomEinwahllink direkt: https:\/\/is.gd\/y6mWZz\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)Mit Pfarrerin Dr. Milena Hasselmann 20.00 UhrBreathing Space: Touching, peaceful musical moments in turbulent timesKonzert im Rahmen von Sounding Jerusalem FestivalTickets unter https:\/\/www.tickettailor.com\/events\/soundingjerusalem\/1717749Mit Werken von Rossi, Bach, Cantata, Azarashvili\u2026Mark\u00e9ta Janou\u0161kov\u00e1 \u2013 Violine, Tommaso Benciolini \u2013 Fl\u00f6te, Armin Egger &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Unsere Veranstaltungen im August 2025&#8221;<\/span><\/a><\/p>","protected":false},"author":8,"featured_media":1273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[256,124,125,281],"class_list":["post-20744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-altstadt","tag-erloeserkirche","tag-jerusalem","tag-newsletter","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Veranstaltungen im August 2025 - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Veranstaltungen im August 2025 - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Sa, 02.08.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 19.00 Uhr (18.00 Uhr deutscher Zeit)Friedensgebet per ZoomEinwahllink direkt: https:\/\/is.gd\/y6mWZz\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)Mit Pfarrerin Dr. Milena Hasselmann 20.00 UhrBreathing Space: Touching, peaceful musical moments in turbulent timesKonzert im Rahmen von Sounding Jerusalem FestivalTickets unter https:\/\/www.tickettailor.com\/events\/soundingjerusalem\/1717749Mit Werken von Rossi, Bach, Cantata, Azarashvili\u2026Mark\u00e9ta Janou\u0161kov\u00e1 \u2013 Violine, Tommaso Benciolini \u2013 Fl\u00f6te, Armin Egger &hellip; Continue reading &quot;Unsere Veranstaltungen im August 2025&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T08:40:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T08:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/05\/Erlo\u0308serkirche-2299-e1745829584253.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"853\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bilhan Rechtman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bilhan Rechtman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/\"},\"author\":{\"name\":\"Bilhan Rechtman\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\"},\"headline\":\"Unsere Veranstaltungen im August 2025\",\"datePublished\":\"2025-08-01T08:40:23+00:00\",\"dateModified\":\"2025-08-01T08:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/\"},\"wordCount\":455,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Erlo\u0308serkirche-2299-e1745829584253.jpg\",\"keywords\":[\"Altstadt\",\"Erl\u00f6serkirche\",\"Jerusalem\",\"Newsletter\"],\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/\",\"name\":\"Unsere Veranstaltungen im August 2025 - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Erlo\u0308serkirche-2299-e1745829584253.jpg\",\"datePublished\":\"2025-08-01T08:40:23+00:00\",\"dateModified\":\"2025-08-01T08:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Erlo\u0308serkirche-2299-e1745829584253.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Erlo\u0308serkirche-2299-e1745829584253.jpg\",\"width\":853,\"height\":880},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/08\\\/01\\\/unsere-veranstaltungen-im-august-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Veranstaltungen im August 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\",\"name\":\"Bilhan Rechtman\",\"sameAs\":[\"http:\\\/\\\/www.evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/bilhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Veranstaltungen im August 2025 - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/","og_locale":"en_GB","og_type":"article","og_title":"Unsere Veranstaltungen im August 2025 - Evangelisch in Jerusalem","og_description":"Sa, 02.08.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 19.00 Uhr (18.00 Uhr deutscher Zeit)Friedensgebet per ZoomEinwahllink direkt: https:\/\/is.gd\/y6mWZz\u00a0(oder Zoom-ID: 976 8331 9026, Code: 391044)Mit Pfarrerin Dr. Milena Hasselmann 20.00 UhrBreathing Space: Touching, peaceful musical moments in turbulent timesKonzert im Rahmen von Sounding Jerusalem FestivalTickets unter https:\/\/www.tickettailor.com\/events\/soundingjerusalem\/1717749Mit Werken von Rossi, Bach, Cantata, Azarashvili\u2026Mark\u00e9ta Janou\u0161kov\u00e1 \u2013 Violine, Tommaso Benciolini \u2013 Fl\u00f6te, Armin Egger &hellip; Continue reading \"Unsere Veranstaltungen im August 2025\"","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2025-08-01T08:40:23+00:00","article_modified_time":"2025-08-01T08:40:25+00:00","og_image":[{"width":853,"height":880,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/05\/Erlo\u0308serkirche-2299-e1745829584253.jpg","type":"image\/jpeg"}],"author":"Bilhan Rechtman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bilhan Rechtman","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/"},"author":{"name":"Bilhan Rechtman","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7"},"headline":"Unsere Veranstaltungen im August 2025","datePublished":"2025-08-01T08:40:23+00:00","dateModified":"2025-08-01T08:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/"},"wordCount":455,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/05\/Erlo\u0308serkirche-2299-e1745829584253.jpg","keywords":["Altstadt","Erl\u00f6serkirche","Jerusalem","Newsletter"],"articleSection":["Allgemein"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/","name":"Unsere Veranstaltungen im August 2025 - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/05\/Erlo\u0308serkirche-2299-e1745829584253.jpg","datePublished":"2025-08-01T08:40:23+00:00","dateModified":"2025-08-01T08:40:25+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/05\/Erlo\u0308serkirche-2299-e1745829584253.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/05\/Erlo\u0308serkirche-2299-e1745829584253.jpg","width":853,"height":880},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/08\/01\/unsere-veranstaltungen-im-august-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Unsere Veranstaltungen im August 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7","name":"Bilhan Rechtman","sameAs":["http:\/\/www.evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/bilhan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=20744"}],"version-history":[{"count":1,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20744\/revisions"}],"predecessor-version":[{"id":20745,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20744\/revisions\/20745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=20744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=20744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=20744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}