{"id":20375,"date":"2025-05-30T12:12:52","date_gmt":"2025-05-30T09:12:52","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=20375"},"modified":"2025-05-30T12:28:07","modified_gmt":"2025-05-30T09:28:07","slug":"unsere-veranstaltungen-im-juni-2025","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/","title":{"rendered":"Unsere Veranstaltungen im Juni 2025"},"content":{"rendered":"<p><a><br><\/a>So, 01.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst mit Abendmahl<br><\/strong>Predigt: Propst Joachim Lenz<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Im Anschluss an den Gottesdienst ist Stimmabgabe zur KGR-Wahl m\u00f6glich.<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 03.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.30 Uhr<br><strong>Gemeindeversammlung mit Wahl des Kirchengemeinderats<br>der Evangelischen Gemeinde deutscher Sprache zu Jerusalem<\/strong><br>Alle Gemeindemitglieder sind eingeladen zur Versammlung um 19:30 Uhr.<br>Bereits ab 19.00 Uhr gibt es einen Imbiss mit Kartoffelsalat und W\u00fcrstchen.<br>Refektorium der Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mi, 04.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten.<br>Mit Pfarrerin Ines Fischer und Kirchenmusikdirektor Peter-Michael Seifried<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>Sa, 07.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Pfarrerin Ines Fischer<\/p>\n\n\n\n<p>So, 08.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr <em>Pfingsten<\/em><br><strong>Gottesdienst mit Abendmahl am Pfingstsonntag<br><\/strong>Predigt: Pfarrerin Ines Fischer;<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mo, 09.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.00 Uhr <em>Pfingsten<\/em><br><strong>\u00d6kumenischer Gottesdienst zu Pfingsten in der Dormitio<br><\/strong>Leitung: P. Elias Pfiffi OSB, Predigt: Propst Joachim Lenz<br>Dormitio-Abtei auf dem Zion<\/p>\n\n\n\n<p>Di, 10.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 20.00-21.30 Uhr<br><strong>Die Samaritaner in Israel und in den pal\u00e4stinensischen Gebieten \u2013<br>eine Minderheit so zahlreich wie die Sterne am Himmel?<br><\/strong>Gemeindeabend mit Prof. Dr. Stefan Schorch, Hebr\u00e4ische Universit\u00e4t<br>Refektorium der Erl\u00f6serkirche, Muristan Road, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mi, 11.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten.<br>Mit Pfarrerin Ines Fischer und Kirchenmusikdirektor Peter-Michael Seifried<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>Do 12.06.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 19.00 Uhr<br><strong>Zwischent\u00f6ne \u2013 Konzert im Kerzenlicht in der Himmelfahrtkirche<br><\/strong>Mit Gedichten von Nelly Sachs u.a. und Musik aus verschiedenen kulturellen Kontexten.<br>Orgel: Kirchenmusikdirektor Peter-Michael Seifried, Oud: Dr. Elias Lahham u.a.<br>Der Eintritt ist frei, wir bitten am Ausgang herzlich um Spenden, die dem<br>Auguste Victoria-Krankenhaus zugutekommen.<br>Assumption Church and Caf\u00e9 Auguste Victoria on the Mount of Olives<\/p>\n\n\n\n<p>Fr, 13.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 14.00-18.00 Uhr<br><strong>Kochkurs mit Margaret Younan<\/strong><br>Bitte Anmelden unter <a href=\"mailto:himmelfahrt@evajerusalem.org\">himmelfahrt@evajerusalem.org<\/a><br>Caf\u00e9 Auguste Victoria in der Himmelfahrtkirche<\/p>\n\n\n\n<p>Sa, 14.06. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 4.45 Uhr<br><strong>Sonnenaufgang mit Andacht auf dem Turm der Himmelfahrtkirche<br><\/strong>Mit Pfarrerin Ines Fischer<br>Treffpunkt vor dem Eingang der Himmelfahrtkirche auf dem \u00d6lberg<\/p>\n\n\n\n<p>06.00-12.00 Uhr<br><strong>Fr\u00fchst\u00fccksbuffet<br><\/strong>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>8.00 Uhr<br><strong>F\u00fchrung <\/strong><em>in englischer Sprache<\/em><strong>: The History of The Auguste Victoria Compound<br><\/strong>Mit Pfarrerin Ines Fischer<\/p>\n\n\n\n<p>9.00 Uhr<br><strong>F\u00fchrung <\/strong><em>in deutscher Sprache<\/em><strong>: Die Geschichte des Auguste Victoria-Gel\u00e4ndes<br><\/strong>Mit Pfarrerin Ines Fischer<\/p>\n\n\n\n<p>10.10-10.40 Uhr<br><strong>Orgelkonzert \u201eThe Mighty Sauer (1910)\u201c in der Himmelfahrtkirche, <\/strong><br>um 9.55 Uhr gibt es eine Einf\u00fchrung auf der Empore. <br>Mit Kirchenmusikdirektor Peter-Michael Seifried<\/p>\n\n\n\n<p>12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Pfarrerin Hasselmann<\/p>\n\n\n\n<p>So, 15.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst am Sonntag Trinitatis<\/strong><br>Predigt: Pfarrerin Milena Hasselmann<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 17.06. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 20.00 Uhr<br><strong>Gespr\u00e4ch mit dem Leiter des Vertretungsb\u00fcros der Bundesrepublik Deutschland in Ramallah, S.E. Oliver Owcza<br><\/strong>danach <strong>Abschlussabend der Saison<\/strong> mit Sommerbowle<br>Kreuzgang der Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mi, 18.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten.<br>Mit Pfarrerin Ines Fischer und Kirchenmusikdirektor Peter-Michael Seifried<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>Sa, 21.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>15.00-17.00 Uhr<br><strong>Familiennachmittag auf der Auguste<\/strong><br>Mit Charlie und seinem Team<br>Anmeldung unter pastorin@evajerusalem.org<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Pfarrerin Ines Fischer<\/p>\n\n\n\n<p>So, 22.06.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 10.30 Uhr<br><strong>Gottesdienst am 1. Sonntag nach Trinitatis<\/strong><br>Liturgie: Pfarrerin Ines Fischer; Predigt: Pfarrerin Sally Azar<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 24.06. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 20.00 Uhr<br><strong>Stummfilm mit Live-Musik: \u00bbIntoleranz\u00ab (UA 1916)<\/strong><br>197 Minuten, Regie: David Wark Griffith, Eintritt frei<br>Am Steinway-Fl\u00fcgel: Kirchenmusikdirektor Peter-Michael Seifried<br>Johanniterkapelle der Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mi, 25.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten.<br>Mit Pfarrerin Ines Fischer und Kirchenmusikdirektor Peter-Michael Seifried<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>Sa, 28.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Propst Joachim Lenz<\/p>\n\n\n\n<p>So, 29.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst am 2. Sonntag nach Trinitatis<\/strong><br>Predigt: Propst Joachim Lenz<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>","protected":false},"excerpt":{"rendered":"<p>So, 01.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 UhrGottesdienst mit AbendmahlPredigt: Propst Joachim LenzMusik: Kirchenmusikdirektor Peter-Michael SeifriedIm Anschluss an den Gottesdienst ist Stimmabgabe zur KGR-Wahl m\u00f6glich.Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem Di, 03.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.30 UhrGemeindeversammlung mit Wahl des Kirchengemeinderatsder Evangelischen Gemeinde deutscher Sprache zu JerusalemAlle Gemeindemitglieder sind eingeladen zur Versammlung um 19:30 Uhr.Bereits ab 19.00 Uhr gibt es einen &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Unsere Veranstaltungen im Juni 2025&#8221;<\/span><\/a><\/p>","protected":false},"author":8,"featured_media":16408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[256,101,213,125,5,281],"class_list":["post-20375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-altstadt","tag-gemeindeabend","tag-gottesdienst","tag-jerusalem","tag-konzert","tag-newsletter","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Veranstaltungen im Juni 2025 - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Veranstaltungen im Juni 2025 - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"So, 01.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 UhrGottesdienst mit AbendmahlPredigt: Propst Joachim LenzMusik: Kirchenmusikdirektor Peter-Michael SeifriedIm Anschluss an den Gottesdienst ist Stimmabgabe zur KGR-Wahl m\u00f6glich.Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem Di, 03.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.30 UhrGemeindeversammlung mit Wahl des Kirchengemeinderatsder Evangelischen Gemeinde deutscher Sprache zu JerusalemAlle Gemeindemitglieder sind eingeladen zur Versammlung um 19:30 Uhr.Bereits ab 19.00 Uhr gibt es einen &hellip; Continue reading &quot;Unsere Veranstaltungen im Juni 2025&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T09:12:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T09:28:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/EK_tagsueber-Muristan-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1922\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bilhan Rechtman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bilhan Rechtman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/\"},\"author\":{\"name\":\"Bilhan Rechtman\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\"},\"headline\":\"Unsere Veranstaltungen im Juni 2025\",\"datePublished\":\"2025-05-30T09:12:52+00:00\",\"dateModified\":\"2025-05-30T09:28:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/\"},\"wordCount\":894,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/EK_tagsueber-Muristan-scaled.jpg\",\"keywords\":[\"Altstadt\",\"Gemeindeabend\",\"Gottesdienst\",\"Jerusalem\",\"Konzert\",\"Newsletter\"],\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/\",\"name\":\"Unsere Veranstaltungen im Juni 2025 - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/EK_tagsueber-Muristan-scaled.jpg\",\"datePublished\":\"2025-05-30T09:12:52+00:00\",\"dateModified\":\"2025-05-30T09:28:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/EK_tagsueber-Muristan-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/EK_tagsueber-Muristan-scaled.jpg\",\"width\":1922,\"height\":2560,\"caption\":\"Herbst 2023, Bilhan Derin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2025\\\/05\\\/30\\\/unsere-veranstaltungen-im-juni-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Veranstaltungen im Juni 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\",\"name\":\"Bilhan Rechtman\",\"sameAs\":[\"http:\\\/\\\/www.evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/bilhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Veranstaltungen im Juni 2025 - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/","og_locale":"en_GB","og_type":"article","og_title":"Unsere Veranstaltungen im Juni 2025 - Evangelisch in Jerusalem","og_description":"So, 01.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 UhrGottesdienst mit AbendmahlPredigt: Propst Joachim LenzMusik: Kirchenmusikdirektor Peter-Michael SeifriedIm Anschluss an den Gottesdienst ist Stimmabgabe zur KGR-Wahl m\u00f6glich.Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem Di, 03.06.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.30 UhrGemeindeversammlung mit Wahl des Kirchengemeinderatsder Evangelischen Gemeinde deutscher Sprache zu JerusalemAlle Gemeindemitglieder sind eingeladen zur Versammlung um 19:30 Uhr.Bereits ab 19.00 Uhr gibt es einen &hellip; Continue reading \"Unsere Veranstaltungen im Juni 2025\"","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2025-05-30T09:12:52+00:00","article_modified_time":"2025-05-30T09:28:07+00:00","og_image":[{"width":1922,"height":2560,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/EK_tagsueber-Muristan-scaled.jpg","type":"image\/jpeg"}],"author":"Bilhan Rechtman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bilhan Rechtman","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/"},"author":{"name":"Bilhan Rechtman","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7"},"headline":"Unsere Veranstaltungen im Juni 2025","datePublished":"2025-05-30T09:12:52+00:00","dateModified":"2025-05-30T09:28:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/"},"wordCount":894,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/EK_tagsueber-Muristan-scaled.jpg","keywords":["Altstadt","Gemeindeabend","Gottesdienst","Jerusalem","Konzert","Newsletter"],"articleSection":["Allgemein"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/","name":"Unsere Veranstaltungen im Juni 2025 - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/EK_tagsueber-Muristan-scaled.jpg","datePublished":"2025-05-30T09:12:52+00:00","dateModified":"2025-05-30T09:28:07+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/EK_tagsueber-Muristan-scaled.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/EK_tagsueber-Muristan-scaled.jpg","width":1922,"height":2560,"caption":"Herbst 2023, Bilhan Derin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2025\/05\/30\/unsere-veranstaltungen-im-juni-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Unsere Veranstaltungen im Juni 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7","name":"Bilhan Rechtman","sameAs":["http:\/\/www.evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/bilhan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=20375"}],"version-history":[{"count":3,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20375\/revisions"}],"predecessor-version":[{"id":20379,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/20375\/revisions\/20379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/16408"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=20375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=20375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=20375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}