{"id":19273,"date":"2024-11-01T12:16:34","date_gmt":"2024-11-01T10:16:34","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=19273"},"modified":"2024-11-15T12:44:05","modified_gmt":"2024-11-15T10:44:05","slug":"unsere-veranstaltungen-im-november-2024","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/","title":{"rendered":"Unsere Veranstaltungen im November 2024"},"content":{"rendered":"<p>Sa, 02.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<\/strong><br>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>17.00 Uhr<br><strong>Vorabendgottesdienst unserer Gemeinde in Latrun<br><\/strong>mit Abendmahlsfeier; gleichzeitig ist Kindergottesdienst.<br>Im Anschluss sind alle zum Abendessen (Mitbring-Buffet) eingeladen.<br>Predigt: Pfarrerin Ines Fischer, Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Mitfahrgelegenheiten bitte unter <a href=\"mailto:propstei@evajerusalem.org\">propstei@evajerusalem.org<\/a> anfragen und anbieten.<br>Kommunit\u00e4t der Jesusbruderschaft, Latrun, Ramle<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<br>Mit Propst Joachim Lenz<\/p>\n\n\n\n<p>So, 03.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst am 23. Sonntag nach Trinitatis<br><\/strong>Predigt: Pfarrerin Ines Fischer, Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 05.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 20.00-21.30 Uhr<br><strong>Die religi\u00f6sen Siedler und ihre Theologie<br><\/strong>Gemeindeabend mit Tamar Avraham, Judaistin und Islamwissenschaftlerin<br>Refektorium der Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mi, 06.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten mit Pfarrerin Ines Fischer<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung<\/p>\n\n\n\n<p>Fr, 08.11. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 16.30 Uhr-19.00 Uhr<br><strong>Laternenbasteln zu St. Martin und Laternenumzug<br><\/strong>Kinder- und Familiennachmittag auf der Auguste mit anschlie\u00dfendem Abendessen<br>Mit Pfarrerin Ines Fischer. Anmeldungen unter <a href=\"mailto:pastorin@evajerusalem.org\">pastorin@evajerusalem.org<\/a><br>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg<\/p>\n\n\n\n<p>Sa, 09.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>mit Pfr.in Ines Fischer<br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<\/p>\n\n\n\n<p>So, 10.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10.30 Uhr<br><strong>Gottesdienst mit Abendmahl <\/strong>am Drittletzten Sonntag des Kirchenjahres<br>Predigt: Propst Joachim Lenz; Musik: Julia Schmelkina<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 12.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 20.00-21.30 Uhr<br><strong>Die Arbeit eines Korrespondenten in Israel und den besetzten Gebieten<br><\/strong>Gemeindeabend mit Jan-Christoph Kitzler, ARD Tel Aviv<br>Refektorium der Erl\u00f6serkirche, Muristan Road 5, Altstadt<\/p>\n\n\n\n<p>Mi, 13.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten mit Pfarrerin Ines Fischer<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>Sa, 16.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 06.00 Uhr<br><strong>Sonnenaufgang mit Andacht auf dem Turm der Himmelfahrtkirche<br><\/strong>Mit Pfarrerin Ines Fischer<br>Treffpunkt vor dem Eingang der Himmelfahrtkirche auf dem Auguste Victoria-Gel\u00e4nde.<\/p>\n\n\n\n<p>07.00-12.00 Uhr<br><strong>Fr\u00fchst\u00fccksbuffet<br><\/strong>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung.<\/p>\n\n\n\n<p>8.00 Uhr<br><strong>The Church of the Ascension between 1927 and 1950 <\/strong><em>in englischer Sprache<br><\/em>F\u00fchrung mit Pfarrerin Ines Fischer durch die Himmelfahrtkirche auf dem \u00d6lberg<\/p>\n\n\n\n<p>9.00 Uhr<br><strong>Die Himmelfahrtkirche in den Jahren 1927 bis 1950 <\/strong><em>in deutscher Sprache<br><\/em>F\u00fchrung mit Pfarrerin Ines Fischer durch die Himmelfahrtkirche auf dem \u00d6lberg<\/p>\n\n\n\n<p>10.10-10.40 Uhr<br><strong>Orgelkonzert in der Himmelfahrtkirche<br><\/strong>ab 9.55 Uhr gibt es eine Einf\u00fchrung auf der Empore<br>Mit Kirchenmusikdirektor Peter-Michael Seifried<\/p>\n\n\n\n<p>12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<br><\/strong>Mit Christiane Glitscher-Kr\u00fcger<br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<\/p>\n\n\n\n<p>So, 17.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10:30 Uhr<br><strong>Gottesdienst am Vorletzten Sonntag im Kirchenjahr (Volkstrauertag)<br><\/strong>Predigt: Pfarrerin Ines Fischer<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Di, 19.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 18.00-19.45 Uhr<br><strong>Kantoreiprobe in der Bibliothek<br><\/strong>(unter Vorbehalt: Bitte informieren Sie sich \u00fcber unsere Website).<br>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Bibliothek der Propstei, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>20.00-21.30 Uhr<br><strong>Die Heiligkeit Jerusalems im Islam<br><\/strong>Gemeindeabend mit Dr. Hannelies Koloska, Theologin und Arabistin an der<br>Hebr\u00e4ischen Universit\u00e4t in Jerusalem<br>Refektorium der Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mi, 20.11. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.00 Uhr<br><strong>Bu\u00df- und Bettag<br><\/strong>Predigt: Propst Joachim Lenz, Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Fr, 22.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 14.00-16.30 Uhr<br><strong>Kochkurs mit Margaret Younan<\/strong><br>Wir kochen Kousa Mashi und Weinbl\u00e4tter<br>Anmeldung \u00fcber: himmelfahrt@evajerusalem.org<br>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg<\/p>\n\n\n\n<p>Sa, 23.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 Uhr<br><strong>Orgelmatinee in der Erl\u00f6serkirche<br><\/strong>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Mit Kirchengemeinder\u00e4tin Diet Koster<br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<\/p>\n\n\n\n<p>So, 24.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 10:30 Uhr<br><strong>Gottesdienst mit Abendmahl am Ewigkeitssonntag<br><\/strong>anschlie\u00dfend gemeinsamer <strong>Gang zum Friedhof<\/strong> auf dem Zion<br>Predigt: Propst Joachim Lenz<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>&nbsp;15.00 Uhr<br><strong>Wort und Musik zum Kirchenjahresende<br><\/strong>Lesung und Gebet: Propst Joachim Lenz<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br>Erl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem<\/p>\n\n\n\n<p>Mo, 25.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 19.00 Uhr<br><strong>Konzert in der Himmelfahrtkirche<\/strong><br>Mit Orgel, Querfl\u00f6te und Oud: Christiane Peterseim, <br>Dr. Elias Lahme und Kirchenmusikdirektor Peter-Michael Seifried<br>Himmelfahrtkirche auf dem \u00d6lberg<\/p>\n\n\n\n<p>Di, 26.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 18.00-19.45 Uhr<br><strong>Kantoreiprobe in der Bibliothek<br><\/strong>(unter Vorbehalt: Bitte informieren Sie sich aktuell \u00fcber unsere Website)<br>Mit Kirchenmusikdirektor Peter-Michael Seifried<br>Bibliothek der Propstei, Muristan Road 5, Altstadt von Jerusalem&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>20.00-22.30 Uhr<br><strong>Stummfilm mit Live-Musik \u201eNathan der Weise\u201c<br><\/strong>Regie: Manfred Noa, D 1922, Eintritt frei<br>Am Steinway-Fl\u00fcgel: Kirchenmusikdirektor Peter-Michael Seifried<br>Johanniterkapelle der Erl\u00f6serkirche, Muristan Road 5, Altstadt<\/p>\n\n\n\n<p>Mi, 27.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 17.30 Uhr<br><strong>Taiz\u00e9-Andacht in der Himmelfahrtkirche<\/strong><br>Singen \u2013 schweigen \u2013 beten mit Pfarrerin Ines Fischer<br>Musik: Kirchenmusikdirektor Peter-Michael Seifried<br><strong>Im Anschluss: Beisammensein<\/strong> mit Abendessen im Caf\u00e9 Auguste Victoria.<br>Himmelfahrtkirche und Caf\u00e9 Auguste Victoria auf dem \u00d6lberg. Ohne Anmeldung<\/p>\n\n\n\n<p>Sa, 30.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 14.00-17.00 (voraussichtlich, auf der Webseite gibt es aktuelle Infos)<br><strong>Adventsnachmittag der Gemeinde im Refektorium<\/strong><br>Propstei, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>19.00 Uhr (18.00 Uhr deutscher Zeit)<br><strong>Friedensgebet per Zoom<\/strong><br>Mit Kirchengemeinder\u00e4tin Diet Koster<br>Einwahllink direkt: <a href=\"https:\/\/is.gd\/y6mWZz\">https:\/\/is.gd\/y6mWZz<\/a>&nbsp;(oder Zoom-ID: 976 8331 9026, Code: 391044)<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sa, 02.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 UhrOrgelmatinee in der Erl\u00f6serkircheMit Kirchenmusikdirektor Peter-Michael SeifriedErl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem 17.00 UhrVorabendgottesdienst unserer Gemeinde in Latrunmit Abendmahlsfeier; gleichzeitig ist Kindergottesdienst.Im Anschluss sind alle zum Abendessen (Mitbring-Buffet) eingeladen.Predigt: Pfarrerin Ines Fischer, Musik: Kirchenmusikdirektor Peter-Michael SeifriedMitfahrgelegenheiten bitte unter propstei@evajerusalem.org anfragen und anbieten.Kommunit\u00e4t der Jesusbruderschaft, Latrun, Ramle 19.00 Uhr (18.00 Uhr deutscher &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Unsere Veranstaltungen im November 2024&#8221;<\/span><\/a><\/p>","protected":false},"author":8,"featured_media":16414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[256,124,125,281],"class_list":["post-19273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-altstadt","tag-erloeserkirche","tag-jerusalem","tag-newsletter","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Veranstaltungen im November 2024 - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Veranstaltungen im November 2024 - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Sa, 02.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 UhrOrgelmatinee in der Erl\u00f6serkircheMit Kirchenmusikdirektor Peter-Michael SeifriedErl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem 17.00 UhrVorabendgottesdienst unserer Gemeinde in Latrunmit Abendmahlsfeier; gleichzeitig ist Kindergottesdienst.Im Anschluss sind alle zum Abendessen (Mitbring-Buffet) eingeladen.Predigt: Pfarrerin Ines Fischer, Musik: Kirchenmusikdirektor Peter-Michael SeifriedMitfahrgelegenheiten bitte unter propstei@evajerusalem.org anfragen und anbieten.Kommunit\u00e4t der Jesusbruderschaft, Latrun, Ramle 19.00 Uhr (18.00 Uhr deutscher &hellip; Continue reading &quot;Unsere Veranstaltungen im November 2024&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-01T10:16:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-15T10:44:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/Erloeser-in-Daemmerung-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1922\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bilhan Rechtman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bilhan Rechtman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/\"},\"author\":{\"name\":\"Bilhan Rechtman\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\"},\"headline\":\"Unsere Veranstaltungen im November 2024\",\"datePublished\":\"2024-11-01T10:16:34+00:00\",\"dateModified\":\"2024-11-15T10:44:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/\"},\"wordCount\":952,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Erloeser-in-Daemmerung-1-scaled.jpg\",\"keywords\":[\"Altstadt\",\"Erl\u00f6serkirche\",\"Jerusalem\",\"Newsletter\"],\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/\",\"name\":\"Unsere Veranstaltungen im November 2024 - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Erloeser-in-Daemmerung-1-scaled.jpg\",\"datePublished\":\"2024-11-01T10:16:34+00:00\",\"dateModified\":\"2024-11-15T10:44:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Erloeser-in-Daemmerung-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Erloeser-in-Daemmerung-1-scaled.jpg\",\"width\":2560,\"height\":1922,\"caption\":\"Erl\u00f6ser in D\u00e4mmerung, 2023, Bilhan Derin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/11\\\/01\\\/unsere-veranstaltungen-im-november-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Veranstaltungen im November 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\",\"name\":\"Bilhan Rechtman\",\"sameAs\":[\"http:\\\/\\\/www.evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/bilhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Veranstaltungen im November 2024 - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/","og_locale":"en_GB","og_type":"article","og_title":"Unsere Veranstaltungen im November 2024 - Evangelisch in Jerusalem","og_description":"Sa, 02.11.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 12.00-12.30 UhrOrgelmatinee in der Erl\u00f6serkircheMit Kirchenmusikdirektor Peter-Michael SeifriedErl\u00f6serkirche, Muristan Road 1, Altstadt von Jerusalem 17.00 UhrVorabendgottesdienst unserer Gemeinde in Latrunmit Abendmahlsfeier; gleichzeitig ist Kindergottesdienst.Im Anschluss sind alle zum Abendessen (Mitbring-Buffet) eingeladen.Predigt: Pfarrerin Ines Fischer, Musik: Kirchenmusikdirektor Peter-Michael SeifriedMitfahrgelegenheiten bitte unter propstei@evajerusalem.org anfragen und anbieten.Kommunit\u00e4t der Jesusbruderschaft, Latrun, Ramle 19.00 Uhr (18.00 Uhr deutscher &hellip; Continue reading \"Unsere Veranstaltungen im November 2024\"","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2024-11-01T10:16:34+00:00","article_modified_time":"2024-11-15T10:44:05+00:00","og_image":[{"width":2560,"height":1922,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/Erloeser-in-Daemmerung-1-scaled.jpg","type":"image\/jpeg"}],"author":"Bilhan Rechtman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bilhan Rechtman","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/"},"author":{"name":"Bilhan Rechtman","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7"},"headline":"Unsere Veranstaltungen im November 2024","datePublished":"2024-11-01T10:16:34+00:00","dateModified":"2024-11-15T10:44:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/"},"wordCount":952,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/Erloeser-in-Daemmerung-1-scaled.jpg","keywords":["Altstadt","Erl\u00f6serkirche","Jerusalem","Newsletter"],"articleSection":["Allgemein"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/","name":"Unsere Veranstaltungen im November 2024 - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/Erloeser-in-Daemmerung-1-scaled.jpg","datePublished":"2024-11-01T10:16:34+00:00","dateModified":"2024-11-15T10:44:05+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/Erloeser-in-Daemmerung-1-scaled.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/08\/Erloeser-in-Daemmerung-1-scaled.jpg","width":2560,"height":1922,"caption":"Erl\u00f6ser in D\u00e4mmerung, 2023, Bilhan Derin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/11\/01\/unsere-veranstaltungen-im-november-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Unsere Veranstaltungen im November 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7","name":"Bilhan Rechtman","sameAs":["http:\/\/www.evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/bilhan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/19273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=19273"}],"version-history":[{"count":6,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/19273\/revisions"}],"predecessor-version":[{"id":19415,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/19273\/revisions\/19415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/16414"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=19273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=19273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=19273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}