{"id":18733,"date":"2024-09-09T08:43:00","date_gmt":"2024-09-09T05:43:00","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=18733"},"modified":"2024-09-15T16:13:48","modified_gmt":"2024-09-15T13:13:48","slug":"taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/","title":{"rendered":"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September <br>und gemeinsame Mahlzeiten auf dem \u00d6lberg"},"content":{"rendered":"<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong>Taiz\u00e9-Andachten<\/strong><br>gibt es  w\u00f6chentlich, mittwochs um 17.30 Uhr.<br>Anschlie\u00dfend wird eingeladen zum gemeinsamen Abendessen. Anmeldung ist nicht erforderlich.<br>Die Mahlzeit ist kostenlos, \u00fcber eine Spende freuen wir uns nat\u00fcrlich.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/12\/Taize-mit-Kerzen-2.jpg\" alt=\"\" class=\"wp-image-16851\" width=\"277\" height=\"208\" srcset=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/12\/Taize-mit-Kerzen-2.jpg 1024w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/12\/Taize-mit-Kerzen-2-300x225.jpg 300w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/12\/Taize-mit-Kerzen-2-768x576.jpg 768w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/12\/Taize-mit-Kerzen-2-16x12.jpg 16w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Sonnenaufgang auf dem Turm der Himmelfahrtkirche<\/strong><br>mit Morgenandacht und anschlie\u00dfendem Fr\u00fchst\u00fcck ist einmal monatlich im Angebot.<br>Die Termine, auch die genauen Uhrzeiten, stehen in unserem Veranstaltungskalender.<br>Am jeweiligen Samstagvormittag gibt es auch noch ein Konzert auf der Sauer-Orgel in der Himmelfahrtkirche.<\/p>\n\n\n\n<p>F\u00fcr Ende August sieht das so aus:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"699\" height=\"1024\" src=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam-699x1024.jpg\" alt=\"\" class=\"wp-image-18828\" srcset=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam-699x1024.jpg 699w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam-205x300.jpg 205w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam-768x1125.jpg 768w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam-1049x1536.jpg 1049w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam-8x12.jpg 8w, https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2024\/09\/240914-AV-Sonnenaufgang-uam.jpg 1059w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>","protected":false},"excerpt":{"rendered":"<p>Taiz\u00e9-Andachtengibt es w\u00f6chentlich, mittwochs um 17.30 Uhr.Anschlie\u00dfend wird eingeladen zum gemeinsamen Abendessen. Anmeldung ist nicht erforderlich.Die Mahlzeit ist kostenlos, \u00fcber eine Spende freuen wir uns nat\u00fcrlich. Sonnenaufgang auf dem Turm der Himmelfahrtkirchemit Morgenandacht und anschlie\u00dfendem Fr\u00fchst\u00fcck ist einmal monatlich im Angebot.Die Termine, auch die genauen Uhrzeiten, stehen in unserem Veranstaltungskalender.Am jeweiligen Samstagvormittag gibt es auch &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Taiz\u00e9-Andachten, Sonnenaufgang am 14. September <br \/>und gemeinsame Mahlzeiten auf dem \u00d6lberg&#8221;<\/span><\/a><\/p>","protected":false},"author":6,"featured_media":14327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[539,345,549,295],"class_list":["post-18733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-ekd","tag-frieden","tag-friedensgebet","tag-gebet","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Taiz\u00e9-Andachtengibt es w\u00f6chentlich, mittwochs um 17.30 Uhr.Anschlie\u00dfend wird eingeladen zum gemeinsamen Abendessen. Anmeldung ist nicht erforderlich.Die Mahlzeit ist kostenlos, \u00fcber eine Spende freuen wir uns nat\u00fcrlich. Sonnenaufgang auf dem Turm der Himmelfahrtkirchemit Morgenandacht und anschlie\u00dfendem Fr\u00fchst\u00fcck ist einmal monatlich im Angebot.Die Termine, auch die genauen Uhrzeiten, stehen in unserem Veranstaltungskalender.Am jeweiligen Samstagvormittag gibt es auch &hellip; Continue reading &quot;Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T05:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-15T13:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/05\/Auguste-Sunset.png\" \/>\n\t<meta property=\"og:image:width\" content=\"757\" \/>\n\t<meta property=\"og:image:height\" content=\"1209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joachim Lenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joachim Lenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/\"},\"author\":{\"name\":\"Joachim Lenz\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\"},\"headline\":\"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg\",\"datePublished\":\"2024-09-09T05:43:00+00:00\",\"dateModified\":\"2024-09-15T13:13:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/\"},\"wordCount\":95,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Auguste-Sunset.png\",\"keywords\":[\"EKD\",\"Frieden\",\"Friedensgebet\",\"Gebet\"],\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/\",\"name\":\"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Auguste-Sunset.png\",\"datePublished\":\"2024-09-09T05:43:00+00:00\",\"dateModified\":\"2024-09-15T13:13:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Auguste-Sunset.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Auguste-Sunset.png\",\"width\":757,\"height\":1209},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2024\\\/09\\\/09\\\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/ea8e86c01aff849bd324c28bc5574607\",\"name\":\"Joachim Lenz\",\"sameAs\":[\"http:\\\/\\\/evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/propst-jl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/","og_locale":"en_GB","og_type":"article","og_title":"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg - Evangelisch in Jerusalem","og_description":"Taiz\u00e9-Andachtengibt es w\u00f6chentlich, mittwochs um 17.30 Uhr.Anschlie\u00dfend wird eingeladen zum gemeinsamen Abendessen. Anmeldung ist nicht erforderlich.Die Mahlzeit ist kostenlos, \u00fcber eine Spende freuen wir uns nat\u00fcrlich. Sonnenaufgang auf dem Turm der Himmelfahrtkirchemit Morgenandacht und anschlie\u00dfendem Fr\u00fchst\u00fcck ist einmal monatlich im Angebot.Die Termine, auch die genauen Uhrzeiten, stehen in unserem Veranstaltungskalender.Am jeweiligen Samstagvormittag gibt es auch &hellip; Continue reading \"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg\"","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2024-09-09T05:43:00+00:00","article_modified_time":"2024-09-15T13:13:48+00:00","og_image":[{"width":757,"height":1209,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/05\/Auguste-Sunset.png","type":"image\/png"}],"author":"Joachim Lenz","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Joachim Lenz","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/"},"author":{"name":"Joachim Lenz","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607"},"headline":"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg","datePublished":"2024-09-09T05:43:00+00:00","dateModified":"2024-09-15T13:13:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/"},"wordCount":95,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/05\/Auguste-Sunset.png","keywords":["EKD","Frieden","Friedensgebet","Gebet"],"articleSection":["Allgemein"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/","name":"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/05\/Auguste-Sunset.png","datePublished":"2024-09-09T05:43:00+00:00","dateModified":"2024-09-15T13:13:48+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/05\/Auguste-Sunset.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/05\/Auguste-Sunset.png","width":757,"height":1209},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2024\/09\/09\/taize-andachten-sonnenaufgang-und-gemeinsame-mahlzeiten-auf-dem-oelberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Taiz\u00e9-Andachten, Sonnenaufgang am 14. September und gemeinsame Mahlzeiten auf dem \u00d6lberg"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/ea8e86c01aff849bd324c28bc5574607","name":"Joachim Lenz","sameAs":["http:\/\/evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/propst-jl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/18733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=18733"}],"version-history":[{"count":5,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/18733\/revisions"}],"predecessor-version":[{"id":18864,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/18733\/revisions\/18864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/14327"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=18733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=18733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=18733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}