{"id":14873,"date":"2023-07-01T11:51:00","date_gmt":"2023-07-01T08:51:00","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=14873"},"modified":"2023-07-10T15:25:46","modified_gmt":"2023-07-10T12:25:46","slug":"unsere-veranstaltungen-im-juli-2023","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/","title":{"rendered":"Unsere Veranstaltungen im Juli 2023"},"content":{"rendered":"<p>Sa, 01.07. <br>12.00 Uhr <br><strong>Orgelandacht <\/strong>in der Erl\u00f6serkirche <br>Mit KMD Peter-Michael Seifried <br>Erl\u00f6serkirche, Muristan Road 5, Altstadt<br><br>18.00 Uhr <br><strong>Tanzabend in der Himmelfahrtkirche<\/strong> <br>Ein Abend inspiriert aus den Tanzgeschichten in der Bibel. <br>Infos unter: thadina@familie-keinath.com <br>Himmelfahrtkirche auf dem \u00d6lberg<\/p>\n\n\n\n<p><br>So, 02.07. <br>18.00 Uhr <br><strong>Abschlussgottesdienst von \u201eStudium in Israel\u201d <\/strong><br>Der 45. Jahrgang der Studierenden l\u00e4dt herzlich ein, zum Ausklang des Studienjahres. Mit Pfarrerin Dr. Melanie Mordhorst-Mayer und Sondervikar Pfarrer Philipp Huber <br>Anschlie\u00dfend Beisammensein und Snacks im Kreuzgang Johanniterkapelle der Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<br><br>20.00 Uhr <br>Orgelkonzert: Yulia Shmelkina, Russland <br>Internationales Orgel-Festival im Juli <br>Sopran: Svetlana Bendikov, Ukraine <br>Mit Werken von. J. S. Bach, G. F. Handel, D. Buxtehude, F. Schubert, F. Mendelssohn u.a. <br>Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<br><\/p>\n\n\n\n<p>Di, 04.07. <br>20.00 Uhr <br>Stum<strong>mkurzfilm-Festival<\/strong> im Kreuzgang <br>Die Reise zum Mond (1902); Der gro\u00dfe Eisenbahnraub (1903), Laurel und Hardy (1921-1957), Mord in der Orgel (Deutschland, 2014) u.a. <br>Musik: KMD Peter-Michael Seifried; Caf\u00e9 Kreuzgang ist ge\u00f6ffnet. <br>Kreuzgang der Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<br><\/p>\n\n\n\n<p>Do, 06.07. <br>18.00 Uhr <br><strong>Filmabend <\/strong>im Caf\u00e9 Auguste Victoria: The Chosen <br>1. Abend: an vier Donnerstagen im Juli sehen wir die erste Staffel der neuartigen und aufregenden Serie \u00fcber Jesus \u2013 als Sommerprogramm f\u00fcr Volont\u00e4re Gemeinsam anschauen und im Anschluss \u00fcber die Filme sprechen! <br>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg<\/p>\n\n\n\n<p><br>Sa, 08.07. <br>12.00 Uhr <br><strong>Orgelandacht <\/strong>in der Erl\u00f6serkirche <br>Nikita Morozov, Russland\/Israel <br>Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<\/p>\n\n\n\n<p>So, 09.07.<br>20.00 Uhr<br><strong>Orgelkonzert: Nikita Morozov<\/strong>, Russland\/Israel<br>Internationales Orgel-Festival im Juli <br>Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<br><\/p>\n\n\n\n<p>Mo, 10.07. <br>19.00 Uhr <br><strong>Konzert: Moran Ensemble Choir<\/strong> <br>Dirigent: Tom Karni, Musik Direktor: Naomi Faran <br>A capella-Programm, Byrd, Whiteacre, Ligeti <br>Himmelfahrtkirche auf dem \u00d6lberg<br><\/p>\n\n\n\n<p>Do, 13.07. <br>18.00 Uhr <br><strong>Filmabend <\/strong>im Caf\u00e9 Auguste Victoria: The Chosen <br>2. Abend: an vier Donnerstagen im Juli sehen wir die erste Staffel der neuartigen und aufregenden Serie \u00fcber Jesus \u2013 als Sommerprogramm f\u00fcr Volont\u00e4re Gemeinsam anschauen und im Anschluss \u00fcber die Filme sprechen! <br>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg<br><br>Sa, 15.07. <br>12.00 Uhr <br><strong>Orgelandacht <\/strong>in der Erl\u00f6serkirche <br>Mit Dr. Dr. Leonard Sanderman, Gro\u00dfbritanien\/Niederlande <br>Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<br><br>So 16.07. <br>20.00 Uhr <br>Orgelkonzert: Dr. Dr. Leonard Sanderman, Gro\u00dfbritannien\/Niederlande Internationales Internationales Orgel-Festival im Juli <br>Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<br><br>Do, 20.07. <br>18.00 Uhr <br><strong>Filmabend <\/strong>im Caf\u00e9 Auguste Victoria: The Chosen <br>3. Abend: an vier Donnerstagen im Juli sehen wir die erste Staffel der neuartigen und aufregenden Serie \u00fcber Jesus \u2013 als Sommerprogramm f\u00fcr Volont\u00e4re Gemeinsam anschauen und im Anschluss \u00fcber die Filme sprechen! <br>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg<br><\/p>\n\n\n\n<p>Sa, 22.07. <br>12.00 Uhr <br><strong>Orgelandacht<\/strong> in der Erl\u00f6serkirche <br>Mit KMD Peter-Michael Seifried <br>Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<br><\/p>\n\n\n\n<p>So 23.07. <br>20.00 Uhr <br><strong>Orgelkonzert<\/strong>: Dr. Dr. Leonard Sanderman, Gro\u00dfbritannien\/Niederlande Internationales Internationales Orgel-Festival im Juli <br>Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<br><\/p>\n\n\n\n<p>Do, 27.07. <br>18.00 Uhr <br><strong>Filmabend <\/strong>im Caf\u00e9 Auguste Victoria: The Chosen <br>4. Abend: an vier Donnerstagen im Juli sehen wir die erste Staffel der neuartigen und aufregenden Serie \u00fcber Jesus \u2013 als Sommerprogramm f\u00fcr Volont\u00e4re Gemeinsam anschauen und im Anschluss \u00fcber die Filme sprechen! <br>Caf\u00e9 Auguste Victoria auf dem \u00d6lberg<br><\/p>\n\n\n\n<p>Sa, 29.07. <br>12.00 Uhr <br><strong>Orgelandacht <\/strong>in der Erl\u00f6serkirche<br>Mit Leonard Sanderman, Gro\u00dfbritannien\/Niederlande <br>Erl\u00f6serkirche, Muristan Road 5, Altstadt von Jerusalem<br><\/p>\n\n\n\n<p>So, 30.07. <br>20.00 Uhr <br><strong>Orgelkonzert<\/strong>: Hiroko Inoue, Japan\/Russland <br>Internationales Orgel-Festival im Juli <br>Erl\u00f6serkirche, Muristan St. 5, Altstadt von Jerusalem<\/p>","protected":false},"excerpt":{"rendered":"<p>Sa, 01.07. 12.00 Uhr Orgelandacht in der Erl\u00f6serkirche Mit KMD Peter-Michael Seifried Erl\u00f6serkirche, Muristan Road 5, Altstadt 18.00 Uhr Tanzabend in der Himmelfahrtkirche Ein Abend inspiriert aus den Tanzgeschichten in der Bibel. Infos unter: thadina@familie-keinath.com Himmelfahrtkirche auf dem \u00d6lberg So, 02.07. 18.00 Uhr Abschlussgottesdienst von \u201eStudium in Israel\u201d Der 45. Jahrgang der Studierenden l\u00e4dt herzlich &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Unsere Veranstaltungen im Juli 2023&#8221;<\/span><\/a><\/p>","protected":false},"author":8,"featured_media":14875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[324,220],"tags":[256,124,101,213,104,125,5],"class_list":["post-14873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","category-topnachricht","tag-altstadt","tag-erloeserkirche","tag-gemeindeabend","tag-gottesdienst","tag-himmelfahrtkirche","tag-jerusalem","tag-konzert","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Veranstaltungen im Juli 2023 - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Veranstaltungen im Juli 2023 - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Sa, 01.07. 12.00 Uhr Orgelandacht in der Erl\u00f6serkirche Mit KMD Peter-Michael Seifried Erl\u00f6serkirche, Muristan Road 5, Altstadt 18.00 Uhr Tanzabend in der Himmelfahrtkirche Ein Abend inspiriert aus den Tanzgeschichten in der Bibel. Infos unter: thadina@familie-keinath.com Himmelfahrtkirche auf dem \u00d6lberg So, 02.07. 18.00 Uhr Abschlussgottesdienst von \u201eStudium in Israel\u201d Der 45. Jahrgang der Studierenden l\u00e4dt herzlich &hellip; Continue reading &quot;Unsere Veranstaltungen im Juli 2023&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-01T08:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T12:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/07\/Vorne_1--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1898\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bilhan Rechtman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bilhan Rechtman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/\"},\"author\":{\"name\":\"Bilhan Rechtman\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\"},\"headline\":\"Unsere Veranstaltungen im Juli 2023\",\"datePublished\":\"2023-07-01T08:51:00+00:00\",\"dateModified\":\"2023-07-10T12:25:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Vorne_1--scaled.jpg\",\"keywords\":[\"Altstadt\",\"Erl\u00f6serkirche\",\"Gemeindeabend\",\"Gottesdienst\",\"Himmelfahrtkirche\",\"Jerusalem\",\"Konzert\"],\"articleSection\":[\"Newsletter\",\"Topnachricht\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/\",\"name\":\"Unsere Veranstaltungen im Juli 2023 - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Vorne_1--scaled.jpg\",\"datePublished\":\"2023-07-01T08:51:00+00:00\",\"dateModified\":\"2023-07-10T12:25:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Vorne_1--scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Vorne_1--scaled.jpg\",\"width\":1898,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2023\\\/07\\\/01\\\/unsere-veranstaltungen-im-juli-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Veranstaltungen im Juli 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\",\"name\":\"Bilhan Rechtman\",\"sameAs\":[\"http:\\\/\\\/www.evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/bilhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Veranstaltungen im Juli 2023 - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/","og_locale":"en_GB","og_type":"article","og_title":"Unsere Veranstaltungen im Juli 2023 - Evangelisch in Jerusalem","og_description":"Sa, 01.07. 12.00 Uhr Orgelandacht in der Erl\u00f6serkirche Mit KMD Peter-Michael Seifried Erl\u00f6serkirche, Muristan Road 5, Altstadt 18.00 Uhr Tanzabend in der Himmelfahrtkirche Ein Abend inspiriert aus den Tanzgeschichten in der Bibel. Infos unter: thadina@familie-keinath.com Himmelfahrtkirche auf dem \u00d6lberg So, 02.07. 18.00 Uhr Abschlussgottesdienst von \u201eStudium in Israel\u201d Der 45. Jahrgang der Studierenden l\u00e4dt herzlich &hellip; Continue reading \"Unsere Veranstaltungen im Juli 2023\"","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2023-07-01T08:51:00+00:00","article_modified_time":"2023-07-10T12:25:46+00:00","og_image":[{"width":1898,"height":2560,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/07\/Vorne_1--scaled.jpg","type":"image\/jpeg"}],"author":"Bilhan Rechtman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bilhan Rechtman","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/"},"author":{"name":"Bilhan Rechtman","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7"},"headline":"Unsere Veranstaltungen im Juli 2023","datePublished":"2023-07-01T08:51:00+00:00","dateModified":"2023-07-10T12:25:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/"},"wordCount":537,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/07\/Vorne_1--scaled.jpg","keywords":["Altstadt","Erl\u00f6serkirche","Gemeindeabend","Gottesdienst","Himmelfahrtkirche","Jerusalem","Konzert"],"articleSection":["Newsletter","Topnachricht"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/","name":"Unsere Veranstaltungen im Juli 2023 - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/07\/Vorne_1--scaled.jpg","datePublished":"2023-07-01T08:51:00+00:00","dateModified":"2023-07-10T12:25:46+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/07\/Vorne_1--scaled.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2023\/07\/Vorne_1--scaled.jpg","width":1898,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2023\/07\/01\/unsere-veranstaltungen-im-juli-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Unsere Veranstaltungen im Juli 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7","name":"Bilhan Rechtman","sameAs":["http:\/\/www.evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/bilhan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/14873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=14873"}],"version-history":[{"count":2,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/14873\/revisions"}],"predecessor-version":[{"id":14877,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/14873\/revisions\/14877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/14875"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=14873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=14873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=14873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}