{"id":12307,"date":"2022-10-13T10:38:38","date_gmt":"2022-10-13T07:38:38","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?p=12307"},"modified":"2022-10-15T11:44:39","modified_gmt":"2022-10-15T08:44:39","slug":"der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen","status":"publish","type":"post","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/","title":{"rendered":"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen."},"content":{"rendered":"<p style=\"font-style:normal;font-weight:500\">Im Turm sind ab dem 12. Oktober einige Sch\u00e4den zu beseitigen. F\u00fcr eine noch unbestimmte, aber hoffentlich nicht lange Zeit m\u00fcssen wir den Zugang zum Turm daher sperren. <\/p>\n\n\n\n<p>Besuch und Besichtigung der Erl\u00f6serkirche sind auch jetzt m\u00f6glich, herzlich willkommen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Im Turm sind ab dem 12. Oktober einige Sch\u00e4den zu beseitigen. F\u00fcr eine noch unbestimmte, aber hoffentlich nicht lange Zeit m\u00fcssen wir den Zugang zum Turm daher sperren. Besuch und Besichtigung der Erl\u00f6serkirche sind auch jetzt m\u00f6glich, herzlich willkommen!<\/p>","protected":false},"author":8,"featured_media":12375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,181,242],"tags":[],"class_list":["post-12307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-erloeserkirche","category-jerusalem","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen. - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen. - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Im Turm sind ab dem 12. Oktober einige Sch\u00e4den zu beseitigen. F\u00fcr eine noch unbestimmte, aber hoffentlich nicht lange Zeit m\u00fcssen wir den Zugang zum Turm daher sperren. Besuch und Besichtigung der Erl\u00f6serkirche sind auch jetzt m\u00f6glich, herzlich willkommen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-13T07:38:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-15T08:44:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2022\/10\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bilhan Rechtman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bilhan Rechtman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/\"},\"author\":{\"name\":\"Bilhan Rechtman\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\"},\"headline\":\"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen.\",\"datePublished\":\"2022-10-13T07:38:38+00:00\",\"dateModified\":\"2022-10-15T08:44:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/\"},\"wordCount\":52,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg\",\"articleSection\":[\"Allgemein\",\"Erl\u00f6serkirche\",\"Jerusalem\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/\",\"name\":\"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen. - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg\",\"datePublished\":\"2022-10-13T07:38:38+00:00\",\"dateModified\":\"2022-10-15T08:44:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg\",\"width\":678,\"height\":1000,\"caption\":\"Turm der evangelischen Erl\u00f6serkirche, Jerusalem\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/2022\\\/10\\\/13\\\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/person\\\/1a5c46f66365bb12b39ea0ebe03339a7\",\"name\":\"Bilhan Rechtman\",\"sameAs\":[\"http:\\\/\\\/www.evangelisch-in-jerusalem.org\"],\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/en\\\/author\\\/bilhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen. - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/","og_locale":"en_GB","og_type":"article","og_title":"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen. - Evangelisch in Jerusalem","og_description":"Im Turm sind ab dem 12. Oktober einige Sch\u00e4den zu beseitigen. F\u00fcr eine noch unbestimmte, aber hoffentlich nicht lange Zeit m\u00fcssen wir den Zugang zum Turm daher sperren. Besuch und Besichtigung der Erl\u00f6serkirche sind auch jetzt m\u00f6glich, herzlich willkommen!","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_published_time":"2022-10-13T07:38:38+00:00","article_modified_time":"2022-10-15T08:44:39+00:00","og_image":[{"width":678,"height":1000,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2022\/10\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg","type":"image\/jpeg"}],"author":"Bilhan Rechtman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bilhan Rechtman","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#article","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/"},"author":{"name":"Bilhan Rechtman","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7"},"headline":"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen.","datePublished":"2022-10-13T07:38:38+00:00","dateModified":"2022-10-15T08:44:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/"},"wordCount":52,"publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2022\/10\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg","articleSection":["Allgemein","Erl\u00f6serkirche","Jerusalem"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/","name":"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen. - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2022\/10\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg","datePublished":"2022-10-13T07:38:38+00:00","dateModified":"2022-10-15T08:44:39+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2022\/10\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2022\/10\/ErlK_Turm_gelb_gerastert-680x1000-1.jpg","width":678,"height":1000,"caption":"Turm der evangelischen Erl\u00f6serkirche, Jerusalem"},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/2022\/10\/13\/der-turm-der-erloeserkirche-ist-zur-zeit-geschlossen-zur-besichtigung-der-erloeserkirche-sind-sie-willkommen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Der Turm der Erl\u00f6serkirche ist zur Zeit geschlossen."}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]},{"@type":"Person","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/person\/1a5c46f66365bb12b39ea0ebe03339a7","name":"Bilhan Rechtman","sameAs":["http:\/\/www.evangelisch-in-jerusalem.org"],"url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/author\/bilhan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/12307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=12307"}],"version-history":[{"count":2,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/12307\/revisions"}],"predecessor-version":[{"id":12377,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/posts\/12307\/revisions\/12377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/12375"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=12307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/categories?post=12307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=12307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}