{"id":7465,"date":"2021-11-04T10:12:39","date_gmt":"2021-11-04T09:12:39","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?post_type=mec-events&#038;p=7465"},"modified":"2021-11-20T10:17:41","modified_gmt":"2021-11-20T09:17:41","slug":"laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche","status":"publish","type":"mec-events","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/","title":{"rendered":"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[309,124,312,311],"mec_category":[],"class_list":["post-7465","mec-events","type-mec-events","status-publish","hentry","tag-basteln","tag-erloeserkirche","tag-laterne","tag-st-martinsumzug","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-20T09:17:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\\\/\",\"name\":\"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"datePublished\":\"2021-11-04T09:12:39+00:00\",\"dateModified\":\"2021-11-20T09:17:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/","og_locale":"en_GB","og_type":"article","og_title":"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche - Evangelisch in Jerusalem","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_modified_time":"2021-11-20T09:17:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/","name":"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"datePublished":"2021-11-04T09:12:39+00:00","dateModified":"2021-11-20T09:17:41+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/laternenbasteln-und-st-martinsumzug-in-der-erloeserkirche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/"},{"@type":"ListItem","position":3,"name":"Laternenbasteln und St. Martinsumzug in der Erl\u00f6serkirche"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/7465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=7465"}],"version-history":[{"count":2,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/7465\/revisions"}],"predecessor-version":[{"id":7524,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/7465\/revisions\/7524"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=7465"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=7465"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec_category?post=7465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}