{"id":7243,"date":"2021-10-07T11:29:38","date_gmt":"2021-10-07T09:29:38","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?post_type=mec-events&#038;p=7243"},"modified":"2021-10-07T11:29:38","modified_gmt":"2021-10-07T09:29:38","slug":"drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen","status":"publish","type":"mec-events","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/","title":{"rendered":"Drei Jahre Friedensarbeit in  Pal\u00e4stina und Israel:  durchhalten, inne halten, Haltung zeigen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":7244,"comment_status":"closed","ping_status":"closed","template":"","tags":[297,101,125],"mec_category":[96,192],"class_list":["post-7243","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-forum-ziviler-friedensdienst-jerusalem","tag-gemeindeabend","tag-jerusalem","mec_category-gemeindeabend","mec_category-gemeindeveranst","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2021\/10\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/\",\"name\":\"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg\",\"datePublished\":\"2021-10-07T09:29:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/","og_locale":"en_GB","og_type":"article","og_title":"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen - Evangelisch in Jerusalem","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","og_image":[{"width":1810,"height":2560,"url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2021\/10\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/","name":"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/#primaryimage"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2021\/10\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg","datePublished":"2021-10-07T09:29:38+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/#primaryimage","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2021\/10\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2021\/10\/12_10_21_Gemeindeabend_Jana-Grieb-scaled.jpg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/drei-jahre-friedensarbeit-in-palaestina-und-israel-durchhalten-inne-halten-haltung-zeigen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/"},{"@type":"ListItem","position":3,"name":"Drei Jahre Friedensarbeit in Pal\u00e4stina und Israel: durchhalten, inne halten, Haltung zeigen"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/7243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=7243"}],"version-history":[{"count":1,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/7243\/revisions"}],"predecessor-version":[{"id":7245,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/7243\/revisions\/7245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media\/7244"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=7243"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=7243"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec_category?post=7243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}