{"id":2733,"date":"2020-01-09T19:10:32","date_gmt":"2020-01-09T18:10:32","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?post_type=mec-events&#038;p=2733"},"modified":"2020-01-09T19:10:32","modified_gmt":"2020-01-09T18:10:32","slug":"chor-und-orgelkonzert","status":"publish","type":"mec-events","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/chor-und-orgelkonzert\/","title":{"rendered":"Chor- und Orgelkonzert"},"content":{"rendered":"<p>Chor- und Orgelkonzert\u00a0 veranstaltet in Zusammenarbeit mit \u201eIsrael Organ Association\u201c,\u00a0\u201eIsrael Madrigal Singers\u201c und Yuval Rabin (Tel Aviv\/Basel), Orgel<\/p>","protected":false},"excerpt":{"rendered":"<p>Chor- und Orgelkonzert\u00a0 veranstaltet in Zusammenarbeit mit \u201eIsrael Organ Association\u201c,\u00a0\u201eIsrael Madrigal Singers\u201c und Yuval Rabin (Tel Aviv\/Basel), Orgel<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[128,104,108],"mec_category":[126,127],"class_list":["post-2733","mec-events","type-mec-events","status-publish","hentry","tag-chorkonzert","tag-himmelfahrtkirche","tag-orgelkonzert","mec_category-chorkonzert","mec_category-orgelkonzert","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chor- und Orgelkonzert - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/chor-und-orgelkonzert\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chor- und Orgelkonzert - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Chor- und Orgelkonzert\u00a0 veranstaltet in Zusammenarbeit mit \u201eIsrael Organ Association\u201c,\u00a0\u201eIsrael Madrigal Singers\u201c und Yuval Rabin (Tel Aviv\/Basel), Orgel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/chor-und-orgelkonzert\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/chor-und-orgelkonzert\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/chor-und-orgelkonzert\\\/\",\"name\":\"Chor- und Orgelkonzert - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"datePublished\":\"2020-01-09T18:10:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/chor-und-orgelkonzert\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/chor-und-orgelkonzert\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/chor-und-orgelkonzert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chor- und Orgelkonzert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chor- und Orgelkonzert - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/chor-und-orgelkonzert\/","og_locale":"en_GB","og_type":"article","og_title":"Chor- und Orgelkonzert - Evangelisch in Jerusalem","og_description":"Chor- und Orgelkonzert\u00a0 veranstaltet in Zusammenarbeit mit \u201eIsrael Organ Association\u201c,\u00a0\u201eIsrael Madrigal Singers\u201c und Yuval Rabin (Tel Aviv\/Basel), Orgel","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/chor-und-orgelkonzert\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/chor-und-orgelkonzert\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/chor-und-orgelkonzert\/","name":"Chor- und Orgelkonzert - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"datePublished":"2020-01-09T18:10:32+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/chor-und-orgelkonzert\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/events\/chor-und-orgelkonzert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/chor-und-orgelkonzert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/"},{"@type":"ListItem","position":3,"name":"Chor- und Orgelkonzert"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/2733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=2733"}],"version-history":[{"count":1,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/2733\/revisions"}],"predecessor-version":[{"id":2734,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/2733\/revisions\/2734"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=2733"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=2733"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec_category?post=2733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}