{"id":22977,"date":"2026-05-04T09:19:05","date_gmt":"2026-05-04T06:19:05","guid":{"rendered":"https:\/\/www.evangelisch-in-jerusalem.org\/?post_type=mec-events&#038;p=22977"},"modified":"2026-05-04T09:21:41","modified_gmt":"2026-05-04T06:21:41","slug":"gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486","status":"publish","type":"mec-events","link":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/","title":{"rendered":"Gottesdienst<br>\u2723 <font color=\"green\">in Amman<\/font>"},"content":{"rendered":"<p>Leitung: Pr\u00e4dikant <em>Andreas Stechbart<\/em><\/p>\n\n\n\n<p>Musik: <em>Helena Lloyd<\/em><\/p>\n\n\n\n<p>Anschlie\u00dfend wird gemeinsam geredet, gegessen und getrunken. <\/p>","protected":false},"excerpt":{"rendered":"<p>Leitung: Pr\u00e4dikant Andreas Stechbart Musik: Helena Lloyd Anschlie\u00dfend wird gemeinsam geredet, gegessen und getrunken.<\/p>","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[392,370,12],"class_list":["post-22977","mec-events","type-mec-events","status-publish","hentry","mec_category-top-veranstaltung","mec_category-amman","mec_category-gottesdienst","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gottesdienst\u2723 in Amman - Evangelisch in Jerusalem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gottesdienst\u2723 in Amman - Evangelisch in Jerusalem\" \/>\n<meta property=\"og:description\" content=\"Leitung: Pr\u00e4dikant Andreas Stechbart Musik: Helena Lloyd Anschlie\u00dfend wird gemeinsam geredet, gegessen und getrunken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/\" \/>\n<meta property=\"og:site_name\" content=\"Evangelisch in Jerusalem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/erloeserkirche.jerusalem\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T06:21:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\\\/\",\"name\":\"Gottesdienst \u2723 in Amman - Evangelisch in Jerusalem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\"},\"datePublished\":\"2026-05-04T06:19:05+00:00\",\"dateModified\":\"2026-05-04T06:21:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gottesdienst\u2723 in Amman\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#website\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"name\":\"Evangelisch in Jerusalem\",\"description\":\"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#organization\",\"name\":\"German Protestant Institutions in the Holy Land\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"contentUrl\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/EIJ_Logo_500-px.png\",\"width\":500,\"height\":82,\"caption\":\"German Protestant Institutions in the Holy Land\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evangelisch-in-jerusalem.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erloeserkirche.jerusalem\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gottesdienst\u2723 in Amman - Evangelisch in Jerusalem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/","og_locale":"en_GB","og_type":"article","og_title":"Gottesdienst\u2723 in Amman - Evangelisch in Jerusalem","og_description":"Leitung: Pr\u00e4dikant Andreas Stechbart Musik: Helena Lloyd Anschlie\u00dfend wird gemeinsam geredet, gegessen und getrunken.","og_url":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/","og_site_name":"Evangelisch in Jerusalem","article_publisher":"https:\/\/www.facebook.com\/erloeserkirche.jerusalem","article_modified_time":"2026-05-04T06:21:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/","name":"Gottesdienst \u2723 in Amman - Evangelisch in Jerusalem","isPartOf":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website"},"datePublished":"2026-05-04T06:19:05+00:00","dateModified":"2026-05-04T06:21:41+00:00","breadcrumb":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evangelisch-in-jerusalem.org\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/gottesdienst-in-amman-8-138-419-695-646-128-851-578-179-417-254-701-182-508-828-938-486\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.evangelisch-in-jerusalem.org\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.evangelisch-in-jerusalem.org\/events\/"},{"@type":"ListItem","position":3,"name":"Gottesdienst\u2723 in Amman"}]},{"@type":"WebSite","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#website","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","name":"Evangelisch in Jerusalem","description":"Dt. Gemeinde und Stiftungen der EKD im Heiligen Land","publisher":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evangelisch-in-jerusalem.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#organization","name":"German Protestant Institutions in the Holy Land","url":"https:\/\/www.evangelisch-in-jerusalem.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","contentUrl":"https:\/\/www.evangelisch-in-jerusalem.org\/wp-content\/uploads\/2019\/03\/EIJ_Logo_500-px.png","width":500,"height":82,"caption":"German Protestant Institutions in the Holy Land"},"image":{"@id":"https:\/\/www.evangelisch-in-jerusalem.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erloeserkirche.jerusalem"]}]}},"_links":{"self":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/22977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/comments?post=22977"}],"version-history":[{"count":2,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/22977\/revisions"}],"predecessor-version":[{"id":22982,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec-events\/22977\/revisions\/22982"}],"wp:attachment":[{"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/media?parent=22977"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/tags?post=22977"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.evangelisch-in-jerusalem.org\/en\/wp-json\/wp\/v2\/mec_category?post=22977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}